{"id":75884,"date":"2022-06-05T11:18:23","date_gmt":"2022-06-05T09:18:23","guid":{"rendered":"https:\/\/cheznu.tv\/familymanagement\/?post_type=product&#038;p=75884"},"modified":"2025-01-16T02:53:03","modified_gmt":"2025-01-16T01:53:03","slug":"wasserfall-shirt-selina-schnittmuster","status":"publish","type":"product","link":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/","title":{"rendered":"T-Shirt Selina mit Wasserfallkragen \u2702\ufe0f Gr\u00f6sse 36-52 \u2702\ufe0f Schnittmuster zum Herunterladen und Ausdrucken"},"content":{"rendered":"<p>Die Videoanleitung f\u00fcr das T-Shirt mit Wasserfallkragen findest Du hier:<\/p>\n<p><a href=\"https:\/\/cheznu.tv\/familymanagement\/wasserfall-shirt-selina-anleitung\/\">Wasserfall-Shirt Selina Videoanleitung<\/a><\/p>\n<p><a href='https:\/\/www.spoonflower.com\/profiles\/cheznu_tv' target='_blank' title='Spoonflower-Shop mit den ChezNU-Designs'>Unseren neuen Spoonflower-Shop mit Stoffen im ChezNU-Design findest Du hier.<\/a><\/p><p>Neben dem Schnittmuster \/ Schema \/ Anleitung \/ Plotterdatei erh\u00e4ltst Du als Teil der erworbenen Leistung (gilt auch f\u00fcr kostenlose Produkte) auch unseren kostenlosen Newsletter \u201eSchnittmuster-Alarm\u201c. Im Schnittmuster-Alarm informieren wir haupts\u00e4chlich, aber nicht ausschliesslich \u00fcber neue Schnittmuster, Anleitungen, DIY-Projekte, Angebote in unserem Shop, Angebote in anderen Shops, Materialbezugsquellen und allem was irgendwie mit N\u00e4hen, H\u00e4keln, Basteln, Stricken, Upcycling, Organisation und Familie zu tun hat.<\/p><p>Nach Deiner Bestellung erh\u00e4ltst Du die E-Mails automatisch. Du kannst sie allerdings jederzeit und ohne Angabe von Gr\u00fcnden \u00fcber den Link am Ende jeder E-Mail abbestellen.<br>\n\tDie Transparenzerkl\u00e4rung zu unserem Schnittmuster-Alarm findest Du <a title='Transparenzerkl\u00e4rung' href='https:\/\/cheznu.tv\/familymanagement\/transparenzerklaerung-zum-schnittmuster-alarm-newsletter\/' target='_blank'>hier<\/a><\/p>\n<p><strong>Zum Schnittmuster<\/strong><\/p>\n<p>Das Schnittmuster kommt als PDF, wenn es sich um mehrere PDFs handelt packen wir diese in eine ZIP-Datei. Diese muss erst abgespeichert und entpackt werden, bevor man sie auf A4-Papier (Standard) ausdrucken und dann zusammenkleben kann.<br \/>\nFalls Du das noch nie gemacht hast findest Du eine Anleitung in unseren <a href=\"https:\/\/cheznu.tv\/familymanagement\/faq\/\">FAQs<\/a>.<\/p>\n<p>So entf\u00e4llt das l\u00e4stige Schnittmuster kopieren mit teurem Seidenpapier. Das Schnittmuster kann nach dem Zusammenkleben direkt ausgeschnitten werden.<\/p>\n<p>Bitte beachte, die richtigen Druckoptionen einzustellen. Das funktioniert genauso, wie bei Burda.<br \/>\n<a href=\"http:\/\/cheznu.tv\/familymanagement\/burda-schnittmuster-ausdrucken\/\">Burda Schnittmuster Ausdrucken.<\/a><\/p>\n<p>Wie das mit dem Zusammenkleben funktioniert haben wir hier kurz erkl\u00e4rt.<br \/>\n<a href=\"http:\/\/cheznu.tv\/familymanagement\/so-gehts\/\">So geht\u00b4s<\/a>.<\/p>\n<p><a href=\"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2021\/09\/ChezNU-Groessentabelle_fuer_Damen_2021.pdf\">Die Gr\u00f6ssentabelle mit den Massen f\u00fcr Damen findest Du hier.<\/a><\/p>\n<p>Dieser Schnitt darf zu privaten Zwecken und zur Fertigung von Einzelst\u00fccken\/Kleinserien (bis 5 Modelle) unter Nennung der Herkunft verwendet werden (ChezNU.TV). Massenproduktion der fertigen Ware sowie Kopieren, Weitergabe, Abdruck oder Ver\u00f6ffentlichung (auch teilweise) des Schnittmusters bedarf der schriftlichen Genehmigung. Wenn Du Dir nicht sicher bist, schreibe uns einfach kurz eine <a href=\"mailto:nu@cheznu.tv\">E-Mail.<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/klick.cheznu.tv\/pix\/1s8wz4na2zfz75e5\" width=\"1\" height=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das T-Shirt Selina ist ein Shirt mit Wasserfallkragen. Es ist leicht tailliert und hat kurze \u00c4rmel.\u00a0 Es ist <strong>einfach zu n\u00e4hen<\/strong> und herrlich zu tragen.<\/p>\n<p>Das Schnittmuster ist f\u00fcr elastische Stoffe designt. Wir empfehlen fliessenden Jersey Stoffe aus Baumwolle, besser noch Viskosejersey.<\/p>\n<p>Die <strong>Videoanleitungen zum Shirt <\/strong>findest Du weiter unten verlinkt.<\/p>\n<p>Solltest Du dar\u00fcber hinaus noch fragen zum Schnittmuster haben, schreib uns gerne an: <a href=\"mailto:schnittmuster@cheznu.tv\">schnittmuster@cheznu.tv<\/a><\/p>\n","protected":false},"featured_media":75888,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2795,822,810,811],"product_tag":[2413,3322,1482,1484,3321,3320],"class_list":["post-75884","product","type-product","status-publish","has-post-thumbnail","product_cat-hose-kleidung","product_cat-kleidung","product_cat-naehen","product_cat-schnittmuster","product_tag-kurzarm","product_tag-leicht-tailliert","product_tag-shirt","product_tag-t-shirt","product_tag-wasserfallausschnitt","product_tag-wasserfallkragen","first","instock","downloadable","virtual","sold-individually","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schnittmuster: T-Shirt Selina mit Wasserfallkragen<\/title>\n<meta name=\"description\" content=\"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schnittmuster: T-Shirt Selina mit Wasserfallkragen\" \/>\n<meta property=\"og:description\" content=\"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/\" \/>\n<meta property=\"og:site_name\" content=\"ChezNU.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cheznutv\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T01:53:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2022\/06\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cheznu_family\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/\",\"url\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/\",\"name\":\"Schnittmuster: T-Shirt Selina mit Wasserfallkragen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg\",\"datePublished\":\"2022-06-05T09:18:23+00:00\",\"dateModified\":\"2025-01-16T01:53:03+00:00\",\"description\":\"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg\",\"contentUrl\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"T-Shirt Selina mit Wasserfallausschnitt Tragebild nach vorne gebeugt Fokus auf Kragen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/produkt\\\/wasserfall-shirt-selina-schnittmuster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T-Shirt Selina mit Wasserfallkragen \u2702\ufe0f Gr\u00f6sse 36-52 \u2702\ufe0f Schnittmuster zum Herunterladen und Ausdrucken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/#website\",\"url\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/\",\"name\":\"ChezNU.TV\",\"description\":\"N\u00e4hen | Basteln | Haushalt | Familie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cheznu.tv\\\/familymanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schnittmuster: T-Shirt Selina mit Wasserfallkragen","description":"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/","og_locale":"de_DE","og_type":"article","og_title":"Schnittmuster: T-Shirt Selina mit Wasserfallkragen","og_description":"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.","og_url":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/","og_site_name":"ChezNU.TV","article_publisher":"https:\/\/www.facebook.com\/cheznutv\/","article_modified_time":"2025-01-16T01:53:03+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2022\/06\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cheznu_family","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/","url":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/","name":"Schnittmuster: T-Shirt Selina mit Wasserfallkragen","isPartOf":{"@id":"https:\/\/cheznu.tv\/familymanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/#primaryimage"},"image":{"@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/#primaryimage"},"thumbnailUrl":"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2022\/06\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg","datePublished":"2022-06-05T09:18:23+00:00","dateModified":"2025-01-16T01:53:03+00:00","description":"Das T-Shirt Selina ist ein einfaches, leicht tailliertes T-Shirt mit Wasserfallkragen und kurzen \u00c4rmeln. Es ist einfach zu n\u00e4hen.","breadcrumb":{"@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/#primaryimage","url":"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2022\/06\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg","contentUrl":"https:\/\/cheznu.tv\/familymanagement\/wp-content\/uploads\/2022\/06\/T-Shirt-Selina-mit-Wasserfallausschnitt-Tragebild-nach-vorne-gebeugt-Fokus-auf-Kragen.jpg","width":1080,"height":1080,"caption":"T-Shirt Selina mit Wasserfallausschnitt Tragebild nach vorne gebeugt Fokus auf Kragen"},{"@type":"BreadcrumbList","@id":"https:\/\/cheznu.tv\/familymanagement\/produkt\/wasserfall-shirt-selina-schnittmuster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cheznu.tv\/familymanagement\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/cheznu.tv\/familymanagement\/shop\/"},{"@type":"ListItem","position":3,"name":"T-Shirt Selina mit Wasserfallkragen \u2702\ufe0f Gr\u00f6sse 36-52 \u2702\ufe0f Schnittmuster zum Herunterladen und Ausdrucken"}]},{"@type":"WebSite","@id":"https:\/\/cheznu.tv\/familymanagement\/#website","url":"https:\/\/cheznu.tv\/familymanagement\/","name":"ChezNU.TV","description":"N\u00e4hen | Basteln | Haushalt | Familie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cheznu.tv\/familymanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/product\/75884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/comments?post=75884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/media\/75888"}],"wp:attachment":[{"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/media?parent=75884"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/product_brand?post=75884"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/product_cat?post=75884"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cheznu.tv\/familymanagement\/wp-json\/wp\/v2\/product_tag?post=75884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}